{"id":41,"date":"2018-03-08T13:58:29","date_gmt":"2018-03-08T13:58:29","guid":{"rendered":"http:\/\/www.adflora.it\/site\/?page_id=41"},"modified":"2018-03-08T16:11:43","modified_gmt":"2018-03-08T16:11:43","slug":"contatti","status":"publish","type":"page","link":"http:\/\/www.adflora.it\/site\/contatti\/","title":{"rendered":"Contatti"},"content":{"rendered":"<div class=\"caldera-grid\" id=\"caldera_form_1\" data-cf-ver=\"1.9.7\" data-cf-form-id=\"CF5aa13bd575685\"><div id=\"caldera_notices_1\" data-spinner=\"http:\/\/www.adflora.it\/site\/wp-admin\/images\/spinner.gif\"><\/div><form data-instance=\"1\" class=\"CF5aa13bd575685 caldera_forms_form cfajax-trigger\" method=\"POST\" enctype=\"multipart\/form-data\" id=\"CF5aa13bd575685_1\" data-form-id=\"CF5aa13bd575685\" aria-label=\"Contatti\" data-target=\"#caldera_notices_1\" data-template=\"#cfajax_CF5aa13bd575685-tmpl\" data-cfajax=\"CF5aa13bd575685\" data-load-element=\"_parent\" data-load-class=\"cf_processing\" data-post-disable=\"0\" data-action=\"cf_process_ajax_submit\" data-request=\"http:\/\/www.adflora.it\/site\/cf-api\/CF5aa13bd575685\" data-hiderows=\"true\">\r\n<input type=\"hidden\" id=\"_cf_verify_CF5aa13bd575685\" name=\"_cf_verify\" value=\"7e5a91488d\"  data-nonce-time=\"1788377951\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/site\/wp-json\/wp\/v2\/pages\/41\" \/><div id=\"cf2-CF5aa13bd575685_1\"><\/div><input type=\"hidden\" name=\"_cf_frm_id\" value=\"CF5aa13bd575685\">\r\n<input type=\"hidden\" name=\"_cf_frm_ct\" value=\"1\">\r\n<input type=\"hidden\" name=\"cfajax\" value=\"CF5aa13bd575685\">\r\n<input type=\"hidden\" name=\"_cf_cr_pst\" value=\"41\">\r\n<div class=\"hide\" style=\"display:none; overflow:hidden;height:0;width:0;\">\r\n<label>Twitter<\/label><input type=\"text\" name=\"twitter\" value=\"\" autocomplete=\"off\">\r\n<\/div><div id=\"CF5aa13bd575685_1-row-1\"  class=\"row  first_row\"><div  class=\"col-sm-12  single\"><div class=\"\"><p><\n\n<h2 style=\"margin: 15px 20px; text-align: center; color: #006600;\">Dati di contatti<\/h2>\n<p style=\"margin: 15px 20px; text-align: justify; color: #006600;\">Mettiti in contatto con <strong>Ad Hoc Genova S.r.l.<\/strong> per ricevere ulteriori informazioni su AdFlora.<\/p>\n<hr>\n<\/div><div data-field-wrapper=\"fld_8841021\" class=\"form-group\" id=\"fld_8841021_1-wrap\">\r\n\t<label id=\"fld_8841021Label\" for=\"fld_8841021_1\" class=\"control-label\">Ragione Sociale <span aria-hidden=\"true\" role=\"presentation\" class=\"field_required\" style=\"color:#ee0000;\">*<\/span><\/label>\r\n\t<div class=\"\">\r\n\t\t<input   required type=\"text\" data-field=\"fld_8841021\" class=\" form-control\" id=\"fld_8841021_1\" name=\"fld_8841021\" value=\"\" data-type=\"text\" aria-required=\"true\"   aria-labelledby=\"fld_8841021Label\" >\t\t\t<\/div>\r\n<\/div>\r\n<div data-field-wrapper=\"fld_2147782\" class=\"form-group\" id=\"fld_2147782_1-wrap\">\r\n\t<label id=\"fld_2147782Label\" for=\"fld_2147782_1\" class=\"control-label\">Cognome, Nome <span aria-hidden=\"true\" role=\"presentation\" class=\"field_required\" style=\"color:#ee0000;\">*<\/span><\/label>\r\n\t<div class=\"\">\r\n\t\t<input   required type=\"text\" data-field=\"fld_2147782\" class=\" form-control\" id=\"fld_2147782_1\" name=\"fld_2147782\" value=\"\" data-type=\"text\" aria-required=\"true\"   aria-labelledby=\"fld_2147782Label\" >\t\t\t<\/div>\r\n<\/div>\r\n<div data-field-wrapper=\"fld_6009157\" class=\"form-group\" id=\"fld_6009157_1-wrap\">\r\n\t<label id=\"fld_6009157Label\" for=\"fld_6009157_1\" class=\"control-label\">Email <span aria-hidden=\"true\" role=\"presentation\" class=\"field_required\" style=\"color:#ee0000;\">*<\/span><\/label>\r\n\t<div class=\"\">\r\n\t\t<input   required type=\"email\" data-field=\"fld_6009157\" class=\" form-control\" id=\"fld_6009157_1\" name=\"fld_6009157\" value=\"\" data-type=\"email\" aria-required=\"true\"   aria-labelledby=\"fld_6009157Label\" >\t\t\t<\/div>\r\n<\/div>\r\n<div data-field-wrapper=\"fld_4245072\" class=\"form-group\" id=\"fld_4245072_1-wrap\">\r\n\t<label id=\"fld_4245072Label\" for=\"fld_4245072_1\" class=\"control-label\">Numero di telefono <span aria-hidden=\"true\" role=\"presentation\" class=\"field_required\" style=\"color:#ee0000;\">*<\/span><\/label>\r\n\t<div class=\"\">\r\n\t\t<input  data-inputmask=\"'mask': '+99 99 999 9999'\"  required type=\"phone\" data-field=\"fld_4245072\" class=\" form-control\" id=\"fld_4245072_1\" name=\"fld_4245072\" value=\"\" data-type=\"phone\" aria-required=\"true\"   aria-labelledby=\"fld_4245072Label\" >\t\t\t<\/div>\r\n<\/div>\r\n<\/div><\/div><div id=\"CF5aa13bd575685_1-row-2\"  class=\"row \"><div  class=\"col-sm-12  single\"><div class=\"\"><h2 style=\"margin: 15px 20px; text-align: center; color: #006600;\">Come posso aiutarti?<\/h2>\n<p style=\"margin: 15px 20px; text-align: justify; color: #006600;\">Inoltra la tua richiesta. Nel pi\u00f9 breve tempo possibile vi ricontatteremo.<\/p>\n<hr>\n<\/div><\/div><\/div><div id=\"CF5aa13bd575685_1-row-3\"  class=\"row \"><div  class=\"col-sm-12  single\"><div data-field-wrapper=\"fld_7683514\" class=\"form-group\" id=\"fld_7683514_1-wrap\">\r\n\t<label id=\"fld_7683514Label\" for=\"fld_7683514_1\" class=\"control-label\">Testo mail <span aria-hidden=\"true\" role=\"presentation\" class=\"field_required\" style=\"color:#ee0000;\">*<\/span><\/label>\r\n\t<div class=\"\">\r\n\t\t<textarea name=\"fld_7683514\" value=\"\" data-field=\"fld_7683514\" class=\"form-control\" id=\"fld_7683514_1\" rows=\"7\"  required=\"required\"  aria-labelledby=\"fld_7683514Label\" ><\/textarea>\n\t\t\t<\/div>\r\n<\/div>\r\n<\/div><\/div><div id=\"CF5aa13bd575685_1-row-4\"  class=\"row  last_row\"><div  class=\"col-sm-12  single\"><div data-field-wrapper=\"fld_7908577\" class=\"form-group\" id=\"fld_7908577_1-wrap\">\r\n<div class=\"\">\r\n\t<input  class=\"btn btn-default\" type=\"submit\" name=\"fld_7908577\" id=\"fld_7908577_1\" value=\"Invia\" data-field=\"fld_7908577\"  >\n<\/div>\r\n<\/div>\r\n\t<input class=\"button_trigger_1\" type=\"hidden\" name=\"fld_7908577\" id=\"fld_7908577_1_btn\" value=\"\" data-field=\"fld_7908577\"  \/>\n<\/div><\/div><\/form>\r\n<\/div>\r\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"fullwidth.php","meta":{"footnotes":""},"class_list":["post-41","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contatti - AdFlora - Soluzione Gestionale per Florovivaisti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.adflora.it\/site\/contatti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contatti - AdFlora - Soluzione Gestionale per Florovivaisti\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.adflora.it\/site\/contatti\/\" \/>\n<meta property=\"og:site_name\" content=\"AdFlora - Soluzione Gestionale per Florovivaisti\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-08T16:11:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/contatti\\\/\",\"url\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/contatti\\\/\",\"name\":\"Contatti - AdFlora - Soluzione Gestionale per Florovivaisti\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/#website\"},\"datePublished\":\"2018-03-08T13:58:29+00:00\",\"dateModified\":\"2018-03-08T16:11:43+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/contatti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.adflora.it\\\/site\\\/contatti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/contatti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contatti\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/#website\",\"url\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/\",\"name\":\"AdFlora - Soluzione Gestionale per Florovivaisti\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/#organization\",\"name\":\"AdHoc Genova S.r.l.\",\"url\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/AdhocGenova.jpg\",\"contentUrl\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/AdhocGenova.jpg\",\"width\":1661,\"height\":951,\"caption\":\"AdHoc Genova S.r.l.\"},\"image\":{\"@id\":\"http:\\\/\\\/www.adflora.it\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6MDVm0drVrmXeN9DKFBAqQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contatti - AdFlora - Soluzione Gestionale per Florovivaisti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.adflora.it\/site\/contatti\/","og_locale":"it_IT","og_type":"article","og_title":"Contatti - AdFlora - Soluzione Gestionale per Florovivaisti","og_url":"http:\/\/www.adflora.it\/site\/contatti\/","og_site_name":"AdFlora - Soluzione Gestionale per Florovivaisti","article_modified_time":"2018-03-08T16:11:43+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.adflora.it\/site\/contatti\/","url":"http:\/\/www.adflora.it\/site\/contatti\/","name":"Contatti - AdFlora - Soluzione Gestionale per Florovivaisti","isPartOf":{"@id":"http:\/\/www.adflora.it\/site\/#website"},"datePublished":"2018-03-08T13:58:29+00:00","dateModified":"2018-03-08T16:11:43+00:00","breadcrumb":{"@id":"http:\/\/www.adflora.it\/site\/contatti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.adflora.it\/site\/contatti\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.adflora.it\/site\/contatti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.adflora.it\/site\/"},{"@type":"ListItem","position":2,"name":"Contatti"}]},{"@type":"WebSite","@id":"http:\/\/www.adflora.it\/site\/#website","url":"http:\/\/www.adflora.it\/site\/","name":"AdFlora - Soluzione Gestionale per Florovivaisti","description":"","publisher":{"@id":"http:\/\/www.adflora.it\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.adflora.it\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"http:\/\/www.adflora.it\/site\/#organization","name":"AdHoc Genova S.r.l.","url":"http:\/\/www.adflora.it\/site\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.adflora.it\/site\/#\/schema\/logo\/image\/","url":"http:\/\/www.adflora.it\/site\/wp-content\/uploads\/2018\/03\/AdhocGenova.jpg","contentUrl":"http:\/\/www.adflora.it\/site\/wp-content\/uploads\/2018\/03\/AdhocGenova.jpg","width":1661,"height":951,"caption":"AdHoc Genova S.r.l."},"image":{"@id":"http:\/\/www.adflora.it\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UC6MDVm0drVrmXeN9DKFBAqQ"]}]}},"_links":{"self":[{"href":"http:\/\/www.adflora.it\/site\/wp-json\/wp\/v2\/pages\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.adflora.it\/site\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.adflora.it\/site\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.adflora.it\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.adflora.it\/site\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":1,"href":"http:\/\/www.adflora.it\/site\/wp-json\/wp\/v2\/pages\/41\/revisions"}],"predecessor-version":[{"id":42,"href":"http:\/\/www.adflora.it\/site\/wp-json\/wp\/v2\/pages\/41\/revisions\/42"}],"wp:attachment":[{"href":"http:\/\/www.adflora.it\/site\/wp-json\/wp\/v2\/media?parent=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}